{"id":29281,"date":"2020-05-02T09:58:36","date_gmt":"2020-05-02T07:58:36","guid":{"rendered":"https:\/\/www.infracenter.fr\/?page_id=29281"},"modified":"2020-05-02T10:04:19","modified_gmt":"2020-05-02T08:04:19","slug":"comptable","status":"publish","type":"page","link":"https:\/\/www.infracenter.fr\/index.php\/comptable\/","title":{"rendered":"Comptable"},"content":{"rendered":"<p>[vc_row css=\u00a0\u00bb.vc_custom_1509351079558{padding-top: 80px !important;padding-bottom: 100px !important;}\u00a0\u00bb el_id=\u00a0\u00bbabout\u00a0\u00bb][vc_column]<div id=\"ultimate-heading-34226a575b416532d\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-34226a575b416532d uvc-3347 \" data-hspacer=\"line_with_icon\" data-hline_width=\"120\" data-hicon_type=\"selector\" data-hborder_style=\"solid\" data-hborder_height=\"3\" data-hborder_color=\"#f3615a\" data-icon_width=\"18\" data-hfixer=\"10\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-34226a575b416532d h1'  data-responsive-json-new='{\"font-size\":\"desktop:42px;mobile_landscape:34px;\",\"line-height\":\"desktop:52px;mobile_landscape:44px;\"}' ><h1 style=\"font-weight:bold;\">Comptable<\/h1><\/div><div class=\"uvc-heading-spacer line_with_icon\" style=\"margin-bottom:60px;height:18px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#f3615a;font-size:18px;display:inline-block;\">\n\t<i class=\"icomoon-font-awesome-14x14-chevron-down\"><\/i>\n<\/div><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h3>\u00c0 propos de l&#8217;emploi<\/h3>\n<p>Le r\u00f4le est de garantir les bons contr\u00f4les financiers sur lesquels notre entreprise doit s&rsquo;appuyer.\u00a0Une structure all\u00e9g\u00e9e et plate dans une culture ax\u00e9e sur la performance vous donne une ind\u00e9pendance significative pour fa\u00e7onner votre r\u00f4le et vos contributions \u00e0 la performance de notre \u00e9quipe et de notre entreprise.<\/p>\n<p>Relevant directement du directeur financier MEA, ce poste offrira \u00e9galement au bon candidat la possibilit\u00e9 d&rsquo;avoir un impact sur tous les aspects de notre fonction comptable.\u00a0Ce poste est responsable de toutes les fonctions de comptabilit\u00e9, de contr\u00f4le interne et de fiscalit\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<h3>Devoirs et responsabilit\u00e9s<\/h3>\n<p>Les principales responsabilit\u00e9s comprennent le processus de cl\u00f4ture mensuelle, aider \u00e0 la pr\u00e9paration des d\u00e9clarations de revenus annuelles et assurer les contr\u00f4les appropri\u00e9s et la conformit\u00e9 dans toute l&rsquo;organisation.<\/p>\n<p>Responsable des fonctions comptables, assurant l&rsquo;ach\u00e8vement rapide et pr\u00e9cis de toutes les t\u00e2ches financi\u00e8res et comptables.<\/p>\n<p>Conduisez des politiques et des proc\u00e9dures coh\u00e9rentes et efficaces pendant le processus de cl\u00f4ture mensuelle, y compris les rapprochements de comptes, les audits de rapprochement de comptes, les soumissions, les lettres de d\u00e9claration et les \u00e9critures d&rsquo;ajustement.<\/p>\n<p>Pr\u00e9paration et coordination de tous les audits requis (internes et externes).<\/p>\n<p>Suivi de tous les plans d&rsquo;actions d&rsquo;audit.<\/p>\n<p>Effectuer une analyse financi\u00e8re des comptes du bilan pour garantir la conformit\u00e9, l&rsquo;int\u00e9grit\u00e9 des soldes des comptes \/ rapports financiers et l&rsquo;efficacit\u00e9 des processus op\u00e9rationnels.<\/p>\n<p>Assurer les rapports financiers au Finance Manager MEA dans le syst\u00e8me de reporting.<\/p>\n<p>&nbsp;<\/p>\n<h3>Exp\u00e9rience et qualifications<\/h3>\n<p>BS ou sup\u00e9rieur en administration des affaires \/ comptabilit\u00e9.<\/p>\n<p>3 ans d&rsquo;exp\u00e9rience pertinente en comptabilit\u00e9 \/ finance d&rsquo;entreprise.<\/p>\n<p>Connaissance d\u00e9taill\u00e9e de la comptabilit\u00e9 et d&rsquo;autres normes de rapport pertinentes.<\/p>\n<p>Bonnes comp\u00e9tences en communication \u00e9crite et verbale.<\/p>\n<p>Ma\u00eetrise de l&rsquo;application MS Office.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f29270-o1\" lang=\"fr-FR\" dir=\"ltr\" data-wpcf7-id=\"29270\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/29281#wpcf7-f29270-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulaire de contact\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"29270\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.4\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"fr_FR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f29270-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<h2>Informations personnelles\n<\/h2>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"genre\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"wpcf7-list-item first\"><input type=\"radio\" name=\"genre\" value=\"Mr.\" checked=\"checked\" \/><span class=\"wpcf7-list-item-label\">Mr.<\/span><\/span><span class=\"wpcf7-list-item last\"><input type=\"radio\" name=\"genre\" value=\"Mme.\" \/><span class=\"wpcf7-list-item-label\">Mme.<\/span><\/span><\/span><\/span><br \/>\n<label> Nom*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n<\/p>\n<p><label> Pr\u00e9nom*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-prename\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-prename\" \/><\/span> <\/label>\n<\/p>\n<p><label> Age*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"age\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"age\" \/><\/span> <\/label>\n<\/p>\n<p><label> Email*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Compte linkedin<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"linkedin\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"linkedin\" \/><\/span> <\/label>\n<\/p>\n<p><label> Exp\u00e9rience<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"exp\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"exp\" \/><\/span> <\/label>\n<\/p>\n<p><label> Attentes<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"attentes\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"attentes\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><label> Motivations<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"motivations\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"motivations\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><label> Message<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><label> CV (Max 5M , pdf|doc|docx)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"cv\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".pdf,.doc,.docx\" aria-invalid=\"false\" type=\"file\" name=\"cv\" \/><\/span> <\/label>\n<\/p>\n<div id=\"cf7sr-6a575b4166157\" class=\"cf7sr-g-recaptcha\" data-theme=\"light\" data-type=\"image\" data-size=\"normal\" data-sitekey=\"6LccWWIpAAAAAJzH2UtzkQc_6ITblRuImgJsRvis\"><\/div><span class=\"wpcf7-form-control-wrap cf7sr-recaptcha\" data-name=\"cf7sr-recaptcha\"><input type=\"hidden\" name=\"cf7sr-recaptcha\" value=\"\" class=\"wpcf7-form-control\"><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envoyer\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css=\u00a0\u00bb.vc_custom_1509351079558{padding-top: 80px !important;padding-bottom: 100px !important;}\u00a0\u00bb el_id=\u00a0\u00bbabout\u00a0\u00bb][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] \u00c0 propos de l&#8217;emploi Le r\u00f4le est de garantir les bons contr\u00f4les financiers sur lesquels notre entreprise doit s&rsquo;appuyer.\u00a0Une structure all\u00e9g\u00e9e et plate dans une culture ax\u00e9e sur la performance vous donne une ind\u00e9pendance significative pour fa\u00e7onner votre r\u00f4le et vos contributions \u00e0 la performance de notre \u00e9quipe&hellip;<\/p>\n","protected":false},"author":1,"featured_media":569,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-microsite.php","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":""},"class_list":["post-29281","page","type-page","status-publish","has-post-thumbnail","hentry","description-off"],"_links":{"self":[{"href":"https:\/\/www.infracenter.fr\/index.php\/wp-json\/wp\/v2\/pages\/29281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infracenter.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.infracenter.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.infracenter.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infracenter.fr\/index.php\/wp-json\/wp\/v2\/comments?post=29281"}],"version-history":[{"count":3,"href":"https:\/\/www.infracenter.fr\/index.php\/wp-json\/wp\/v2\/pages\/29281\/revisions"}],"predecessor-version":[{"id":29286,"href":"https:\/\/www.infracenter.fr\/index.php\/wp-json\/wp\/v2\/pages\/29281\/revisions\/29286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.infracenter.fr\/index.php\/wp-json\/wp\/v2\/media\/569"}],"wp:attachment":[{"href":"https:\/\/www.infracenter.fr\/index.php\/wp-json\/wp\/v2\/media?parent=29281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}